{"id":3015,"date":"2026-04-15T14:15:35","date_gmt":"2026-04-15T12:15:35","guid":{"rendered":"https:\/\/www.fw-pfaffenhofen-glonn.de\/?p=3015"},"modified":"2026-04-15T14:20:56","modified_gmt":"2026-04-15T12:20:56","slug":"fr","status":"publish","type":"post","link":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/","title":{"rendered":"Fr\u00fchjahrs\u00fcbung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3015\" class=\"elementor elementor-3015\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4859e58a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4859e58a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6693cf95\" data-id=\"6693cf95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4411df28 elementor-widget elementor-widget-heading\" data-id=\"4411df28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fr\u00fchjahrs\u00fcbung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e49bab2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e49bab2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f0f88a7\" data-id=\"7f0f88a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a5955b5 elementor-widget elementor-widget-image\" data-id=\"5a5955b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg\" class=\"attachment-large size-large wp-image-3018\" alt=\"\" srcset=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg 1024w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-300x225.jpg 300w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-768x576.jpg 768w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1536x1152.jpg 1536w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc8ced5 elementor-widget elementor-widget-image\" data-id=\"bc8ced5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3-1024x768.jpg\" class=\"attachment-large size-large wp-image-3019\" alt=\"\" srcset=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3-1024x768.jpg 1024w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3-300x225.jpg 300w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3-768x576.jpg 768w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3-1536x1152.jpg 1536w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung3.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0bf39 elementor-widget elementor-widget-image\" data-id=\"5d0bf39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1-1024x768.jpg\" class=\"attachment-large size-large wp-image-3016\" alt=\"\" srcset=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1-1024x768.jpg 1024w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1-300x225.jpg 300w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1-768x576.jpg 768w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1-1536x1152.jpg 1536w, https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Aprilubung1.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44361c8e\" data-id=\"44361c8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58cc177d elementor-widget elementor-widget-text-editor\" data-id=\"58cc177d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Ernstfall m\u00fcssen wir Hand-in-Hand arbeiten um schnell zu handeln und schlimmeres zu verhindern. Aus diesem Grund haben im April die 3 Gemeindefeuerwehren aus Weitenried, Unterumbach und Pfaffenhofen wieder eine Gemeinde\u00fcbung abgehalten. Ziel war prim\u00e4r der Aufbau einer langen Schlauchleitung und damit die F\u00f6rderung von L\u00f6schwasser an einen eher abgelegenen Hof.<\/p><p>W\u00e4hrend das HLF von Pfaffenhofen direkt zum &#8222;Moaster&#8220;-Hof fuhr, wo ein Scheunenbrand mit einer vermissten Person simuliert wurde, setzten die Kameraden von Weitenried direkt am Ortsrand von Ebersried den Hydrant in Betrieb und pumpten mit Unterst\u00fctzung des TSF von Unterumbach als Unterst\u00fctzerpumpe das Wasser \u00fcber eine ca. 400m lange Schlauchleitung zum HLF. Von dort aus wurden mehrere Rohre f\u00fcr den Au\u00dfenangriff verlegt und ein Trupp unter Atemschutz ging ebenfalls mit Wasser zur Personensuche und Brandbek\u00e4mpfung in die Scheune vor.<\/p><p>Vor lauter Rauch war nicht viel in der Scheune zu erkennen, weshalb recht bald ein L\u00fcfter aufgebaut wurde, um die Scheune von Rauch (und im Ernstfall auch Hitze) zu befreien.<\/p><p>Der Innenangriff musste zwischendurch sogar unterbrochen werden, weil vorne in der Wasserleitung ein Schlauch &#8222;geplatzt&#8220; ist und die Wasserversorgung unterbrochen wurde. In diesem Fall m\u00fcssen die Kameraden aus Selbstschutz sofort das Geb\u00e4ude verlassen.\u00a0<\/p><p>Nachdem die Wasserversorgung wiederhergestellt war, ging der Angriff sofort wieder weiter und der Brandherd konnte gefunden und gel\u00f6scht werden. Nur die vermisste Person lag leider so gut versteckt, dass sie bis zum Schluss nicht gefunden werden konnte. Gl\u00fccklicher Weise war es nur unser Dummy, der vielleicht mit vorhandener K\u00f6rpertemeratur von der W\u00e4rmebildkamera erfasst und somit gerettet worden w\u00e4re.\u00a0<\/p><p>Im Anschluss wurde gemeinsam aufger\u00e4umt und die \u00dcbung besprochen, bevor es im Ger\u00e4tehaus von Weitenried den \u00fcblichen Lohn unseres Ehrenamts gab: A guade Brotzeit!<\/p><p>An dieser Stelle ein gro\u00dfes Dankesch\u00f6n an Familien Trenkler und Pongratz, die uns den Hof zur \u00dcbung bereitgestellt haben. Ohne solche Unterst\u00fctzungen aus der Gemeinde k\u00f6nnten wir uns nicht so professionell auf die vielen unterschiedlichen Einsatzgegebenheiten vorbereiten.<\/p><p>Hier findet ihr noch ein Video der Luft\u00fcberwachung: <a href=\"https:\/\/www.instagram.com\/reel\/DW9iJMDCH06\/?igsh=MWRnY2d3c2lkOHo1eg==\">https:\/\/www.instagram.com\/reel\/DW9iJMDCH06\/?igsh=MWRnY2d3c2lkOHo1eg==<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f9864bd\" data-id=\"3f9864bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6bd182 elementor-widget elementor-widget-heading\" data-id=\"e6bd182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Neueste Beitr\u00e4ge:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14d0251d elementor-widget elementor-widget-elementskit-blog-posts\" data-id=\"14d0251d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-blog-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <div id=\"post-items--14d0251d\" class=\"ekit-row post-items\">\n                    <div class=\"ekit-lg-12 ekit-md-12\">\n\n                                    <div class=\"elementskit-post-image-card\">\n                        <div class=\"elementskit-entry-header\">\n                            \n                            \n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-entry-header END -->\n\n\t\t\t\t\t\t<div class=\"elementskit-post-body \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/07\/05\/jugendleistungspruefung-2026\/\">\n\t\t\t\t\t\tJugendleistungspr\u00fcfung 2026\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"btn-wraper\">\n                                                                            <a class=\"elementskit-btn whitespace--normal\" id=\"\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/07\/05\/jugendleistungspruefung-2026\/\">\n                                            Weiterlesen                                            <i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>                                        <\/a>\n                                    \n                                                                    <\/div>\n                                                    <\/div><!-- .elementskit-post-body END -->\n                    <\/div>\n                \n            <\/div>\n                    <div class=\"ekit-lg-12 ekit-md-12\">\n\n                                    <div class=\"elementskit-post-image-card\">\n                        <div class=\"elementskit-entry-header\">\n                            \n                            \n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-entry-header END -->\n\n\t\t\t\t\t\t<div class=\"elementskit-post-body \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/06\/21\/rettet-kalle-eine-schnitzeljagt-mit-den-feuerfuechsen\/\">\n\t\t\t\t\t\tRettet Kalle! \u2013 Eine Schnitzeljagt&hellip;\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"btn-wraper\">\n                                                                            <a class=\"elementskit-btn whitespace--normal\" id=\"\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/06\/21\/rettet-kalle-eine-schnitzeljagt-mit-den-feuerfuechsen\/\">\n                                            Weiterlesen                                            <i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>                                        <\/a>\n                                    \n                                                                    <\/div>\n                                                    <\/div><!-- .elementskit-post-body END -->\n                    <\/div>\n                \n            <\/div>\n                    <div class=\"ekit-lg-12 ekit-md-12\">\n\n                                    <div class=\"elementskit-post-image-card\">\n                        <div class=\"elementskit-entry-header\">\n                            \n                            \n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-entry-header END -->\n\n\t\t\t\t\t\t<div class=\"elementskit-post-body \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/27\/wir-feiern-die-kinderflamme-und-ein-jahr-kinderfeuerwehr\/\">\n\t\t\t\t\t\tWir feiern die Kinderflamme und&hellip;\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"btn-wraper\">\n                                                                            <a class=\"elementskit-btn whitespace--normal\" id=\"\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/27\/wir-feiern-die-kinderflamme-und-ein-jahr-kinderfeuerwehr\/\">\n                                            Weiterlesen                                            <i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>                                        <\/a>\n                                    \n                                                                    <\/div>\n                                                    <\/div><!-- .elementskit-post-body END -->\n                    <\/div>\n                \n            <\/div>\n                    <div class=\"ekit-lg-12 ekit-md-12\">\n\n                                    <div class=\"elementskit-post-image-card\">\n                        <div class=\"elementskit-entry-header\">\n                            \n                            \n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-entry-header END -->\n\n\t\t\t\t\t\t<div class=\"elementskit-post-body \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/22\/e\/\">\n\t\t\t\t\t\tEine neue Truppfrau und 6&hellip;\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"btn-wraper\">\n                                                                            <a class=\"elementskit-btn whitespace--normal\" id=\"\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/22\/e\/\">\n                                            Weiterlesen                                            <i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>                                        <\/a>\n                                    \n                                                                    <\/div>\n                                                    <\/div><!-- .elementskit-post-body END -->\n                    <\/div>\n                \n            <\/div>\n                <\/div>\n       <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c7e556 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"37c7e556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/aktuelles\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle Beitr\u00e4ge<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fr\u00fchjahrs\u00fcbung Im Ernstfall m\u00fcssen wir Hand-in-Hand arbeiten um schnell zu handeln und schlimmeres zu verhindern. Aus diesem Grund haben im April die 3 Gemeindefeuerwehren aus Weitenried, Unterumbach und Pfaffenhofen wieder eine Gemeinde\u00fcbung abgehalten. Ziel war prim\u00e4r der Aufbau einer langen Schlauchleitung und damit die F\u00f6rderung von L\u00f6schwasser an einen eher abgelegenen Hof. W\u00e4hrend das HLF [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":66,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3015","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\" \/>\n<meta property=\"og:description\" content=\"Fr\u00fchjahrs\u00fcbung Im Ernstfall m\u00fcssen wir Hand-in-Hand arbeiten um schnell zu handeln und schlimmeres zu verhindern. Aus diesem Grund haben im April die 3 Gemeindefeuerwehren aus Weitenried, Unterumbach und Pfaffenhofen wieder eine Gemeinde\u00fcbung abgehalten. Ziel war prim\u00e4r der Aufbau einer langen Schlauchleitung und damit die F\u00f6rderung von L\u00f6schwasser an einen eher abgelegenen Hof. W\u00e4hrend das HLF [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T12:15:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"cat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"cat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/\"},\"author\":{\"name\":\"cat\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#\\\/schema\\\/person\\\/272ceae0ebafbb63b1a38645201b7be5\"},\"headline\":\"Fr\u00fchjahrs\u00fcbung\",\"datePublished\":\"2026-04-15T12:15:35+00:00\",\"dateModified\":\"2026-04-15T12:20:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apriluebung2-1024x768.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/\",\"url\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/\",\"name\":\"Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apriluebung2-1024x768.jpg\",\"datePublished\":\"2026-04-15T12:15:35+00:00\",\"dateModified\":\"2026-04-15T12:20:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apriluebung2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apriluebung2.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/index.php\\\/2026\\\/04\\\/15\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fr\u00fchjahrs\u00fcbung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#website\",\"url\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/\",\"name\":\"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#organization\",\"name\":\"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\",\"url\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Feuerwehr-Pfaffenhofen-Logo-invertiert-header-2.png\",\"contentUrl\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Feuerwehr-Pfaffenhofen-Logo-invertiert-header-2.png\",\"width\":1077,\"height\":500,\"caption\":\"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de\\\/#\\\/schema\\\/person\\\/272ceae0ebafbb63b1a38645201b7be5\",\"name\":\"cat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g\",\"caption\":\"cat\"},\"sameAs\":[\"https:\\\/\\\/www.fw-pfaffenhofen-glonn.de:81\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/","og_locale":"de_DE","og_type":"article","og_title":"Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","og_description":"Fr\u00fchjahrs\u00fcbung Im Ernstfall m\u00fcssen wir Hand-in-Hand arbeiten um schnell zu handeln und schlimmeres zu verhindern. Aus diesem Grund haben im April die 3 Gemeindefeuerwehren aus Weitenried, Unterumbach und Pfaffenhofen wieder eine Gemeinde\u00fcbung abgehalten. Ziel war prim\u00e4r der Aufbau einer langen Schlauchleitung und damit die F\u00f6rderung von L\u00f6schwasser an einen eher abgelegenen Hof. W\u00e4hrend das HLF [&hellip;]","og_url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/","og_site_name":"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","article_published_time":"2026-04-15T12:15:35+00:00","article_modified_time":"2026-04-15T12:20:56+00:00","og_image":[{"url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg","type":"","width":"","height":""}],"author":"cat","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"cat","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#article","isPartOf":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/"},"author":{"name":"cat","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#\/schema\/person\/272ceae0ebafbb63b1a38645201b7be5"},"headline":"Fr\u00fchjahrs\u00fcbung","datePublished":"2026-04-15T12:15:35+00:00","dateModified":"2026-04-15T12:20:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/"},"wordCount":390,"publisher":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#organization"},"image":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg","articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/","url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/","name":"Fr\u00fchjahrs\u00fcbung - Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","isPartOf":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#primaryimage"},"image":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2-1024x768.jpg","datePublished":"2026-04-15T12:15:35+00:00","dateModified":"2026-04-15T12:20:56+00:00","breadcrumb":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#primaryimage","url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2.jpg","contentUrl":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2026\/04\/Apriluebung2.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/2026\/04\/15\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.fw-pfaffenhofen-glonn.de\/"},{"@type":"ListItem","position":2,"name":"Fr\u00fchjahrs\u00fcbung"}]},{"@type":"WebSite","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#website","url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/","name":"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","description":"","publisher":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fw-pfaffenhofen-glonn.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#organization","name":"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V.","url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2023\/06\/Feuerwehr-Pfaffenhofen-Logo-invertiert-header-2.png","contentUrl":"https:\/\/www.fw-pfaffenhofen-glonn.de\/wp-content\/uploads\/2023\/06\/Feuerwehr-Pfaffenhofen-Logo-invertiert-header-2.png","width":1077,"height":500,"caption":"Freiwillige Feuerwehr Pfaffenhofen a. d. Glonn e.V."},"image":{"@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fw-pfaffenhofen-glonn.de\/#\/schema\/person\/272ceae0ebafbb63b1a38645201b7be5","name":"cat","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0cf6b8dcfd258bb1dc369d821ea095831cfc28315b66b4f0a2218307f94b2dd?s=96&d=mm&r=g","caption":"cat"},"sameAs":["https:\/\/www.fw-pfaffenhofen-glonn.de:81"]}]}},"_links":{"self":[{"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/posts\/3015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/comments?post=3015"}],"version-history":[{"count":7,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/posts\/3015\/revisions"}],"predecessor-version":[{"id":3026,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/posts\/3015\/revisions\/3026"}],"wp:attachment":[{"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/media?parent=3015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/categories?post=3015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fw-pfaffenhofen-glonn.de\/index.php\/wp-json\/wp\/v2\/tags?post=3015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}